{"id":21,"count":1,"description":"","link":"https:\/\/romanivilafranca.com\/ca\/category\/delicious\/","name":"Delicious","slug":"delicious","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Delicious archivos - romanivilafranca.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/romanivilafranca.com\/ca\/category\/delicious\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Delicious archivos - romanivilafranca.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/romanivilafranca.com\/ca\/category\/delicious\/\" \/>\n<meta property=\"og:site_name\" content=\"romanivilafranca.com\" \/>\n<meta property=\"og:image\" content=\"https:\/\/romanivilafranca.com\/wp-content\/uploads\/2024\/11\/pixelcut-export-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/category\\\/delicious\\\/\",\"url\":\"https:\\\/\\\/romanivilafranca.com\\\/category\\\/delicious\\\/\",\"name\":\"Delicious archivos - romanivilafranca.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/category\\\/delicious\\\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/category\\\/delicious\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/romanivilafranca.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Delicious\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/#website\",\"url\":\"https:\\\/\\\/romanivilafranca.com\\\/\",\"name\":\"romanivilafranca.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/romanivilafranca.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/#organization\",\"name\":\"romanivilafranca.com\",\"url\":\"https:\\\/\\\/romanivilafranca.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/romanivilafranca.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/pixelcut-export-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/romanivilafranca.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/pixelcut-export-1.jpeg\",\"width\":600,\"height\":600,\"caption\":\"romanivilafranca.com\"},\"image\":{\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Delicious archivos - romanivilafranca.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/romanivilafranca.com\/ca\/category\/delicious\/","og_locale":"ca_ES","og_type":"article","og_title":"Delicious archivos - romanivilafranca.com","og_url":"https:\/\/romanivilafranca.com\/ca\/category\/delicious\/","og_site_name":"romanivilafranca.com","og_image":[{"width":600,"height":600,"url":"https:\/\/romanivilafranca.com\/wp-content\/uploads\/2024\/11\/pixelcut-export-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/romanivilafranca.com\/category\/delicious\/","url":"https:\/\/romanivilafranca.com\/category\/delicious\/","name":"Delicious archivos - romanivilafranca.com","isPartOf":{"@id":"https:\/\/romanivilafranca.com\/#website"},"breadcrumb":{"@id":"https:\/\/romanivilafranca.com\/category\/delicious\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/romanivilafranca.com\/category\/delicious\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/romanivilafranca.com\/"},{"@type":"ListItem","position":2,"name":"Delicious"}]},{"@type":"WebSite","@id":"https:\/\/romanivilafranca.com\/#website","url":"https:\/\/romanivilafranca.com\/","name":"romanivilafranca.com","description":"","publisher":{"@id":"https:\/\/romanivilafranca.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/romanivilafranca.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/romanivilafranca.com\/#organization","name":"romanivilafranca.com","url":"https:\/\/romanivilafranca.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/romanivilafranca.com\/#\/schema\/logo\/image\/","url":"https:\/\/romanivilafranca.com\/wp-content\/uploads\/2024\/11\/pixelcut-export-1.jpeg","contentUrl":"https:\/\/romanivilafranca.com\/wp-content\/uploads\/2024\/11\/pixelcut-export-1.jpeg","width":600,"height":600,"caption":"romanivilafranca.com"},"image":{"@id":"https:\/\/romanivilafranca.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/romanivilafranca.com\/ca\/wp-json\/wp\/v2\/categories\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/romanivilafranca.com\/ca\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/romanivilafranca.com\/ca\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/romanivilafranca.com\/ca\/wp-json\/wp\/v2\/posts?categories=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}