{"id":996,"date":"2024-11-21T22:43:09","date_gmt":"2024-11-21T22:43:09","guid":{"rendered":"https:\/\/romanivilafranca.com\/?page_id=996"},"modified":"2024-11-28T20:45:20","modified_gmt":"2024-11-28T19:45:20","slug":"terminos-y-condiciones","status":"publish","type":"page","link":"https:\/\/romanivilafranca.com\/ca\/terminos-y-condiciones\/","title":{"rendered":"Termes i Condicions"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"996\" class=\"elementor elementor-996\">\n\t\t\t\t<div class=\"elementor-element elementor-element-241e4618 e-flex e-con-boxed e-con e-parent\" data-id=\"241e4618\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37f66760 elementor-widget elementor-widget-text-editor\" data-id=\"37f66760\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"termsContainer\"><div id=\"termsContainer\"><h2>1.<strong>\u00a0Introducci\u00f3n<\/strong><\/h2><p>Estos T\u00e9rminos y condiciones se aplican a este sitio web y a las transacciones relacionadas con nuestros productos y servicios.\u00a0Usted puede estar obligado por contratos adicionales relacionados con su relaci\u00f3n con nosotros o con cualquier producto o servicio que reciba de nosotros.\u00a0Si alguna de las disposiciones de los contratos adicionales entra en conflicto con alguna de las disposiciones de estas Condiciones, las disposiciones de estos contratos adicionales prevalecer\u00e1n.<\/p><h2><strong>2. Vinculaci\u00f3n<\/strong><\/h2><p>Al registrarse en este sitio web, acceder a \u00e9l o utilizarlo de cualquier otro modo, usted acepta someterse a las condiciones que se exponen a continuaci\u00f3n.\u00a0El mero uso de este sitio web implica el conocimiento y la aceptaci\u00f3n de estos T\u00e9rminos y condiciones.\u00a0En algunos casos particulares, tambi\u00e9n podemos pedirle que lo acepte expl\u00edcitamente.<\/p><h2><strong>3. Comunicaci\u00f3n electr\u00f3nica<\/strong><\/h2><p>Al utilizar este sitio web o comunicarse\u00a0con nosotros por medios electr\u00f3nicos, usted acepta y reconoce que podemos comunicarnos con usted electr\u00f3nicamente en nuestro sitio web o enviarle un correo electr\u00f3nico, y acepta que todos los acuerdos, avisos, divulgaciones y otras comunicaciones que le proporcionemos electr\u00f3nicamente satisfacen cualquier requisito legal, incluido, entre otros, el requisito de que dichas comunicaciones sean por escrito.<\/p><h2><strong>4. Propiedad intelectual<\/strong><\/h2><p>Nosotros o nuestros licenciantes poseemos y controlamos todos los derechos de autor y otros derechos de propiedad intelectual en el sitio web, y los datos, la informaci\u00f3n y otros recursos mostrados por o accesibles dentro del sitio web.<\/p><p><em><strong>4.1 Todos los derechos est\u00e1n reservados<\/strong><\/em><\/p><p>A menos que el contenido espec\u00edfico indique lo contrario, no se le concede una licencia ni ning\u00fan otro derecho en virtud de los derechos de autor, marcas comerciales, patentes u otros derechos de propiedad intelectual.\u00a0Esto significa que usted no utilizar\u00e1, copiar\u00e1, reproducir\u00e1, ejecutar\u00e1, mostrar\u00e1, distribuir\u00e1, incrustar\u00e1 en cualquier medio electr\u00f3nico, alterar\u00e1, realizar\u00e1 ingenier\u00eda inversa, descompilar\u00e1, transferir\u00e1, descargar\u00e1, transmitir\u00e1, monetizar\u00e1, vender\u00e1, comercializar\u00e1 o har\u00e1 uso de cualquier recurso de este sitio web en cualquier forma, sin nuestro permiso previo por escrito, excepto y s\u00f3lo en la medida en que se estipule lo contrario en normas de leyes obligatorias (como el derecho de cita).<\/p><h2><strong>5. Propiedad de terceros<\/strong><\/h2><p>Nuestro sitio web puede incluir hiperv\u00ednculos u otras referencias a sitios web de terceros.\u00a0No controlamos ni revisamos el contenido de los sitios web de terceros a los que se accede desde este sitio web.\u00a0Los productos o servicios ofrecidos por otros sitios web estar\u00e1n sujetos a los T\u00e9rminos y Condiciones aplicables de esos terceros.\u00a0Las opiniones expresadas o el material que aparece en esos sitios web no son necesariamente compartidas o respaldadas por nosotros.<\/p><p>No seremos responsables de las pr\u00e1cticas de privacidad o del contenido de estos sitios.\u00a0Usted asume todos los riesgos asociados al uso de estos sitios web y de cualquier servicio de terceros relacionado.\u00a0No aceptaremos ninguna responsabilidad por cualquier p\u00e9rdida o da\u00f1o, sea cual sea la forma en que se produzca, que resulte de la divulgaci\u00f3n por su parte de informaci\u00f3n personal a terceros.<\/p><h2><strong>6. Uso responsable<\/strong><\/h2><p>Al visitar nuestro sitio web, usted se compromete a utilizarlo s\u00f3lo para los fines previstos y seg\u00fan lo permitido por estos T\u00e9rminos, cualquier contrato adicional con nosotros, y aplicables leyes, reglamentos y pr\u00e1cticas en l\u00ednea generalmente aceptadas y directrices de la industria.\u00a0No debe usar nuestro sitio web o nuestros servicios para utilizar, publicar o distribuir cualquier material que consista en (o est\u00e9 vinculado a) software inform\u00e1tico malicioso; utilizar los datos recogidos en nuestro sitio web para cualquier actividad de marketing directo, o llevar a cabo cualquier actividad de recopilaci\u00f3n de datos sistem\u00e1tica o automatizada en o en relaci\u00f3n con nuestro sitio web.<\/p><p>Est\u00e1 estrictamente prohibido realizar cualquier actividad que provoque o pueda provocar da\u00f1os en el sitio web o que interfiera en su funcionamiento, disponibilidad o accesibilidad.<\/p><h2><strong>7. Env\u00edo de ideas<\/strong><\/h2><p>No env\u00ede ideas, inventos, trabajos de autor\u00eda u otra informaci\u00f3n que pueda considerarse su propia propiedad intelectual y que le gustar\u00eda presentarnos, a menos que primero hayamos firmado un acuerdo con respecto a la propiedad intelectual o un acuerdo de no divulgaci\u00f3n. \u00a0Si nos lo comunica en ausencia de dicho acuerdo por escrito, nos concede una licencia mundial, irrevocable, no exclusiva y libre de derechos de autor para utilizar, reproducir, almacenar, adaptar, publicar, traducir y distribuir su contenido en cualquier medio existente o futuro.<\/p><h2><strong>8. Terminaci\u00f3n de uso<\/strong><\/h2><p>Podemos, a nuestra entera discreci\u00f3n, modificar o interrumpir en cualquier momento el acceso, temporal o permanentemente, al sitio web o a cualquier Servicio del mismo.\u00a0Usted acepta que no seremos responsables ante usted ni ante ning\u00fan tercero por cualquier modificaci\u00f3n, suspensi\u00f3n o interrupci\u00f3n de su acceso o uso del sitio web o de cualquier contenido que pueda haber compartido en el sitio web.\u00a0Usted no tendr\u00e1 derecho a ninguna compensaci\u00f3n ni a ning\u00fan otro pago, ni siquiera si se pierden de forma permanente determinadas funciones, configuraciones y\/o cualquier Contenido con el que haya contribuido o en el que haya confiado.\u00a0No debe eludir o evitar, o intentar eludir o evitar, cualquier medida de restricci\u00f3n de acceso en nuestro sitio web.<\/p><h2><strong>9. Garant\u00edas y responsabilidad<\/strong><\/h2><p>Nada de lo dispuesto en esta secci\u00f3n limitar\u00e1 o excluir\u00e1 cualquier garant\u00eda impl\u00edcita por ley que fuera ilegal limitar o excluir.\u00a0Este sitio web y todo su contenido se proporcionan \u201ctal cual\u201d y \u201cseg\u00fan disponibilidad\u201d y pueden incluir inexactitudes o errores tipogr\u00e1ficos.\u00a0Renunciamos expresamente a toda garant\u00eda de cualquier tipo, ya sea expresa o impl\u00edcita, en cuanto a la disponibilidad, precisi\u00f3n o integridad del Contenido. \u00a0No garantizamos que:<\/p><ul><li>Este sitio web o nuestros contenidos cumplir\u00e1n con sus necesidades;<\/li><li>Este sitio web estar\u00e1 disponible de forma ininterrumpida, oportuna, segura o sin errores.<\/li><\/ul><p>Nada de lo contenido en este sitio web constituye o pretende constituir un asesoramiento jur\u00eddico, financiero o m\u00e9dico de ning\u00fan tipo.\u00a0Si necesita asesoramiento, debe consultar a un profesional adecuado.<\/p><p>Las siguientes disposiciones de esta secci\u00f3n se aplicar\u00e1n en la medida m\u00e1xima permitida por la ley aplicable y no limitar\u00e1n ni excluir\u00e1n nuestra responsabilidad con respecto a cualquier asunto que ser\u00eda il\u00edcito o ilegal para nosotros limitar o excluir nuestra responsabilidad. \u00a0En ning\u00fan caso seremos responsables de cualquier da\u00f1o directo o indirecto (incluyendo cualquier da\u00f1o por p\u00e9rdida de beneficios o ingresos, p\u00e9rdida o corrupci\u00f3n de datos, software o base de datos, o p\u00e9rdida o da\u00f1o a la propiedad o a los datos) incurridos por usted o por cualquier tercero, que surja de su acceso o uso de nuestro sitio web.<\/p><p>Salvo en la medida en que cualquier contrato adicional establezca expresamente lo contrario, nuestra responsabilidad m\u00e1xima hacia usted por todos los da\u00f1os que surjan o est\u00e9n relacionados con el sitio web o con cualquier producto o servicio comercializado o vendido a trav\u00e9s del sitio web, independientemente de la forma de acci\u00f3n legal que imponga la responsabilidad (ya sea por contrato, equidad, negligencia, conducta intencionada, agravio o cualquier otra forma) se limitar\u00e1 al precio total que usted nos pag\u00f3 para comprar dichos productos o servicios o utilizar el sitio web.\u00a0Dicho l\u00edmite se aplicar\u00e1 en conjunto a todas sus reclamaciones, acciones y causas de acci\u00f3n de cualquier tipo y naturaleza.<\/p><h2><strong>10. Privacidad<\/strong><\/h2><p>Para acceder a nuestro sitio web y\/o servicios, es posible que se le pida que proporcione cierta informaci\u00f3n sobre usted como parte del proceso de registro.\u00a0Usted se compromete a que toda la informaci\u00f3n que proporcione sea siempre precisa, correcta y actualizada.<\/p><p>Hemos desarrollado una pol\u00edtica para abordar cualquier preocupaci\u00f3n sobre la privacidad que pueda tener.\u00a0Para m\u00e1s informaci\u00f3n, consulte nuestra\u00a0<a href=\"https:\/\/romanivilafranca.com\/ca\/politica-de-privacidad\/\" data-type=\"link\" data-id=\"https:\/\/taniafernandezfotografia.com\/politica-de-privacidad\/\">Declaraci\u00f3n de privacidad\u00a0<\/a>y nuestra\u00a0<a href=\"https:\/\/romanivilafranca.com\/ca\/politica-de-cookies\/\">Pol\u00edtica de cookies<\/a>.<\/p><h2><strong>11. Uso responsable<\/strong><\/h2><p>Nos comprometemos a que los contenidos que ofrecemos sean accesibles para las personas con discapacidad.\u00a0Si tiene una discapacidad y no puede acceder a cualquier parte de nuestro sitio web debido a su discapacidad, le pedimos que nos avise incluyendo una descripci\u00f3n detallada del problema que ha encontrado.\u00a0Si el problema es f\u00e1cilmente identificable y se puede resolver de acuerdo con las herramientas y t\u00e9cnicas de la tecnolog\u00eda de la informaci\u00f3n est\u00e1ndar del sector, lo resolveremos r\u00e1pidamente.<\/p><h2><strong>12. Restricciones a la exportaci\u00f3n \/ Cumplimiento legal<\/strong><\/h2><p>Se proh\u00edbe el acceso al sitio web desde territorios o pa\u00edses donde el Contenido o la compra de los productos o Servicios vendidos en el sitio web es ilegal. \u00a0No puede utilizar este sitio web infringiendo las leyes y reglamentos de exportaci\u00f3n de Espa\u00f1a.<\/p><h2><strong>13. Asignaci\u00f3n y cesiones<\/strong><\/h2><p>Usted no puede ceder, transferir o subcontratar ninguno de sus derechos y\/u obligaciones en virtud de estos T\u00e9rminos y condiciones, en su totalidad o en parte, a ning\u00fan tercero sin nuestro consentimiento previo por escrito.\u00a0Cualquier supuesta cesi\u00f3n en violaci\u00f3n de esta Secci\u00f3n ser\u00e1 nula y sin efecto.<\/p><h2><strong>14. Incumplimientos de estos T\u00e9rminos y condiciones<\/strong><\/h2><p>Sin perjuicio de los dem\u00e1s derechos que nos asisten en virtud de los presentes T\u00e9rminos y Condiciones, si usted incumple estos T\u00e9rminos y Condiciones de cualquier manera, podremos tomar las medidas que consideremos oportunas para hacer frente al incumplimiento, incluyendo la suspensi\u00f3n temporal o permanente de su acceso al sitio web, poni\u00e9ndonos en contacto con su proveedor de servicios de Internet para solicitarle que bloquee su acceso al sitio web, y\/o iniciar acciones legales contra usted.<\/p><h2><strong>15. Indemnizaci\u00f3n<\/strong><\/h2><p>Usted se compromete a indemnizarnos, defendernos y eximirnos de toda reclamaci\u00f3n, responsabilidad, da\u00f1os, p\u00e9rdidas y gastos, relacionados con la violaci\u00f3n de estas condiciones y de las leyes aplicables, incluidos los derechos de propiedad intelectual y los derechos de privacidad.\u00a0Usted nos reembolsar\u00e1 sin demora los da\u00f1os, p\u00e9rdidas, costes y gastos relacionados con dichas reclamaciones o derivados de ellas.<\/p><h2><strong>16. Renuncia<\/strong><\/h2><p>El incumplimiento de cualquiera de las disposiciones establecidas en estos T\u00e9rminos y condiciones y en cualquier Acuerdo, o la falta de ejercicio de cualquier opci\u00f3n de interrupci\u00f3n, no se interpretar\u00e1 como una renuncia a dichas disposiciones y no afectar\u00e1 a la validez de estos T\u00e9rminos y Condiciones o de cualquier Acuerdo o cualquier parte del mismo, ni al derecho posterior de hacer cumplir todas y cada una de las disposiciones.<\/p><h2><strong>17. Idioma<\/strong><\/h2><p>Estos T\u00e9rminos\u00a0y Condiciones se interpretar\u00e1n y analizar\u00e1n exclusivamente en Espa\u00f1ol; castellano.\u00a0Todas las notificaciones y la correspondencia se redactar\u00e1n exclusivamente en ese idioma.<\/p><h2><strong>18. Acuerdo completo<\/strong><\/h2><p>Estos t\u00e9rminos y condiciones, junto con nuestra declaraci\u00f3n de privacidad y nuestra pol\u00edtica de cookies, constituyen el acuerdo completo entre Monica Gadea Munoz<br \/>y t\u00fa en relaci\u00f3n con tu uso de esta web.<\/p><h2><strong>19. Actualizaci\u00f3n de los presentes T\u00e9rminos y Condiciones<\/strong><\/h2><p>Es posible que actualicemos estos T\u00e9rminos y Condiciones de vez en cuando. \u00a0Es su obligaci\u00f3n revisar peri\u00f3dicamente estos T\u00e9rminos y Condiciones para ver si hay cambios o actualizaciones.\u00a0La fecha indicada al principio de estas Condiciones Generales es la \u00faltima fecha de revisi\u00f3n.\u00a0Los cambios a estos T\u00e9rminos y Condiciones entrar\u00e1n en vigencia cuando dichos cambios se publiquen en este sitio web. \u00a0El uso continuado de este sitio web tras la publicaci\u00f3n de cambios o actualizaciones se considerar\u00e1 un aviso de su aceptaci\u00f3n de cumplir y estar sujeto por estos T\u00e9rminos y Condiciones.<\/p><h2><strong>20. Elecci\u00f3n de ley y jurisdicci\u00f3n<\/strong><\/h2><p>Estos T\u00e9rminos y Condiciones se regir\u00e1n por las leyes de Espa\u00f1a.\u00a0Cualquier disputa relacionada con estos T\u00e9rminos y Condiciones estar\u00e1 sujeta a la jurisdicci\u00f3n de los tribunales de Espa\u00f1a. \u00a0Si un tribunal u otra autoridad considera que alguna parte o disposici\u00f3n de estos T\u00e9rminos y Condiciones es inv\u00e1lida y\/o inaplicable en virtud de la legislaci\u00f3n vigente, dicha parte o disposici\u00f3n ser\u00e1 modificada, eliminada y\/o aplicada en la mayor medida permitida para hacer efectiva la intenci\u00f3n de estos T\u00e9rminos y Condiciones. \u00a0Las dem\u00e1s disposiciones no se ver\u00e1n afectadas.<\/p><h2><strong>21. Informaci\u00f3n del contacto<\/strong><\/h2><div><strong>\u00a0<\/strong><\/div><p>Este sitio web es propiedad y est\u00e1 gestionado por Monica Gadea Munoz.<\/p><p><span style=\"color: var(--rr-text-body); font-size: var(--rr-fs-p); font-weight: var(--rr-fw-normal); font-family: var( --e-global-typography-text-font-family ), Sans-serif; text-align: var(--text-align);\">Puedes contactar con nosotros en relaci\u00f3n a estos t\u00e9rminos y condiciones escribi\u00e9ndonos o envi\u00e1ndonos un correo electr\u00f3nico a la siguiente direcci\u00f3n: <\/span>romanivilafranca@gmail.com<a style=\"font-size: var(--rr-fs-p); font-weight: var(--rr-fw-normal); text-align: var(--text-align);\" href=\"mailto:Oscaregea35@gmail.com\">\u00a0<\/a><span style=\"color: var(--rr-text-body); font-size: var(--rr-fs-p); font-weight: var(--rr-fw-normal); font-family: var( --e-global-typography-text-font-family ), Sans-serif; text-align: var(--text-align);\">o en nuestra direcci\u00f3n: <\/span><a style=\"font-size: var(--rr-fs-p); font-weight: var(--rr-fw-normal); text-align: var(--text-align);\" href=\"https:\/\/maps.app.goo.gl\/X1SCpv9nXFAD3ZNZ7\">Carrer de la Palma, 10, 08720 Vilafranca del Pened\u00e8s, Barcelona<\/a><span style=\"color: var(--rr-text-body); font-size: var(--rr-fs-p); font-weight: var(--rr-fw-normal); font-family: var( --e-global-typography-text-font-family ), Sans-serif; text-align: var(--text-align);\">.<\/span><\/p><h2><strong>22. Descargar<\/strong><\/h2><p>Tambi\u00e9n puedes descargar nuestros t\u00e9rminos y condiciones como un PDF.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>1.\u00a0Introducci\u00f3n Estos T\u00e9rminos y condiciones se aplican a este sitio web y a las transacciones relacionadas con nuestros productos y servicios.\u00a0Usted puede estar obligado por contratos adicionales relacionados con su relaci\u00f3n con nosotros o con cualquier producto o servicio que reciba de nosotros.\u00a0Si alguna de las disposiciones de los contratos adicionales entra en conflicto con [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-996","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e9rminos y Condiciones - romanivilafranca.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/romanivilafranca.com\/ca\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9rminos y Condiciones - romanivilafranca.com\" \/>\n<meta property=\"og:description\" content=\"1.\u00a0Introducci\u00f3n Estos T\u00e9rminos y condiciones se aplican a este sitio web y a las transacciones relacionadas con nuestros productos y servicios.\u00a0Usted puede estar obligado por contratos adicionales relacionados con su relaci\u00f3n con nosotros o con cualquier producto o servicio que reciba de nosotros.\u00a0Si alguna de las disposiciones de los contratos adicionales entra en conflicto con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/romanivilafranca.com\/ca\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:site_name\" content=\"romanivilafranca.com\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-28T19:45:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/romanivilafranca.com\/wp-content\/uploads\/2024\/11\/pixelcut-export-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/terminos-y-condiciones\\\/\",\"url\":\"https:\\\/\\\/romanivilafranca.com\\\/terminos-y-condiciones\\\/\",\"name\":\"T\u00e9rminos y Condiciones - romanivilafranca.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/#website\"},\"datePublished\":\"2024-11-21T22:43:09+00:00\",\"dateModified\":\"2024-11-28T19:45:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/terminos-y-condiciones\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/romanivilafranca.com\\\/terminos-y-condiciones\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/terminos-y-condiciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/romanivilafranca.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9rminos y Condiciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/#website\",\"url\":\"https:\\\/\\\/romanivilafranca.com\\\/\",\"name\":\"romanivilafranca.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/romanivilafranca.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/#organization\",\"name\":\"romanivilafranca.com\",\"url\":\"https:\\\/\\\/romanivilafranca.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/romanivilafranca.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/pixelcut-export-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/romanivilafranca.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/pixelcut-export-1.jpeg\",\"width\":600,\"height\":600,\"caption\":\"romanivilafranca.com\"},\"image\":{\"@id\":\"https:\\\/\\\/romanivilafranca.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9rminos y Condiciones - romanivilafranca.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/romanivilafranca.com\/ca\/terminos-y-condiciones\/","og_locale":"ca_ES","og_type":"article","og_title":"T\u00e9rminos y Condiciones - romanivilafranca.com","og_description":"1.\u00a0Introducci\u00f3n Estos T\u00e9rminos y condiciones se aplican a este sitio web y a las transacciones relacionadas con nuestros productos y servicios.\u00a0Usted puede estar obligado por contratos adicionales relacionados con su relaci\u00f3n con nosotros o con cualquier producto o servicio que reciba de nosotros.\u00a0Si alguna de las disposiciones de los contratos adicionales entra en conflicto con [&hellip;]","og_url":"https:\/\/romanivilafranca.com\/ca\/terminos-y-condiciones\/","og_site_name":"romanivilafranca.com","article_modified_time":"2024-11-28T19:45:20+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/romanivilafranca.com\/wp-content\/uploads\/2024\/11\/pixelcut-export-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"10 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/romanivilafranca.com\/terminos-y-condiciones\/","url":"https:\/\/romanivilafranca.com\/terminos-y-condiciones\/","name":"T\u00e9rminos y Condiciones - romanivilafranca.com","isPartOf":{"@id":"https:\/\/romanivilafranca.com\/#website"},"datePublished":"2024-11-21T22:43:09+00:00","dateModified":"2024-11-28T19:45:20+00:00","breadcrumb":{"@id":"https:\/\/romanivilafranca.com\/terminos-y-condiciones\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/romanivilafranca.com\/terminos-y-condiciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/romanivilafranca.com\/terminos-y-condiciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/romanivilafranca.com\/"},{"@type":"ListItem","position":2,"name":"T\u00e9rminos y Condiciones"}]},{"@type":"WebSite","@id":"https:\/\/romanivilafranca.com\/#website","url":"https:\/\/romanivilafranca.com\/","name":"romanivilafranca.com","description":"","publisher":{"@id":"https:\/\/romanivilafranca.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/romanivilafranca.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/romanivilafranca.com\/#organization","name":"romanivilafranca.com","url":"https:\/\/romanivilafranca.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/romanivilafranca.com\/#\/schema\/logo\/image\/","url":"https:\/\/romanivilafranca.com\/wp-content\/uploads\/2024\/11\/pixelcut-export-1.jpeg","contentUrl":"https:\/\/romanivilafranca.com\/wp-content\/uploads\/2024\/11\/pixelcut-export-1.jpeg","width":600,"height":600,"caption":"romanivilafranca.com"},"image":{"@id":"https:\/\/romanivilafranca.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/romanivilafranca.com\/ca\/wp-json\/wp\/v2\/pages\/996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/romanivilafranca.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/romanivilafranca.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/romanivilafranca.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/romanivilafranca.com\/ca\/wp-json\/wp\/v2\/comments?post=996"}],"version-history":[{"count":19,"href":"https:\/\/romanivilafranca.com\/ca\/wp-json\/wp\/v2\/pages\/996\/revisions"}],"predecessor-version":[{"id":2751,"href":"https:\/\/romanivilafranca.com\/ca\/wp-json\/wp\/v2\/pages\/996\/revisions\/2751"}],"wp:attachment":[{"href":"https:\/\/romanivilafranca.com\/ca\/wp-json\/wp\/v2\/media?parent=996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}